{"id":65076,"date":"2024-01-11T12:31:35","date_gmt":"2024-01-11T10:31:35","guid":{"rendered":"https:\/\/shop.torricantine.com\/blog\/was-sind-wein-ablagerungen\/"},"modified":"2024-06-18T15:19:26","modified_gmt":"2024-06-18T13:19:26","slug":"ablagerungen-im-wein","status":"publish","type":"post","link":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/","title":{"rendered":"Was sind Wein-&#8222;Ablagerungen&#8220;?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-text-align-justify\">H\u00e4ufig k\u00f6nnen in Weinen, insbesondere bei Rotweinen und einige Jahre nach der Ernte, Unvollkommenheiten bei der visuellen Untersuchung aufgrund von R\u00fcckst\u00e4nden oder Sedimenten festgestellt werden, die gemeinhin als &#8222;Bodensatz&#8220; bezeichnet werden, weil sie sich am Boden der Flasche absetzen.<\/h2>\n\n<p>Die Bildung dieser Ablagerungen wird durch einen nat\u00fcrlichen Prozess verursacht, der durch die Aggregation und nachfolgende Ausf\u00e4llung fester Substanzen in der fl\u00fcssigen L\u00f6sung des Weins erfolgt, die sich am Boden der Flasche absetzen.<\/p>\n\n<p>Die Eigenschaften dieser Substanzen variieren je nach Art des Weins, seinem Produktionsprozess und der Reifung\/Alterung, die er durchlaufen hat.<\/p>\n\n<p>In Rotweinen k\u00f6nnen sich Ablagerungen bilden, wenn die Pigmente der Traubenbeeren &#8211; die Anthocyane &#8211; sowie einige aromatische Substanzen in Flocken aggregieren und sich anschlie\u00dfend am Boden der Flasche absetzen. Wenn dies geschieht, \u00e4ndert sich auch die Farbe und das Aroma des Weins.<\/p>\n\n<p>Kristalle aus Kalzium- oder Kaliumtartrat bilden sich hingegen, wenn der Wein pl\u00f6tzlichen Temperaturschwankungen ausgesetzt ist, beispielsweise w\u00e4hrend des K\u00fchlprozesses. Dies f\u00fchrt zur Ausf\u00e4llung kleiner Teilchen von Kalziumsulfat oder Tartratsalzen, die sich immer am Boden der Flasche absetzen.<\/p>\n\n<p>Das Vorhandensein solcher Kristalle schafft kein Problem f\u00fcr die Integrit\u00e4t des Weins, vielmehr zeigt es, dass der Wein sehr wenige Behandlungen durchlaufen hat.<\/p>\n\n<p>Auch w\u00e4hrend der Fermentation k\u00f6nnen sich Hefezellen und Zellr\u00fcckst\u00e4nde der Fermentation absetzen, besonders wenn der Wein nicht vollst\u00e4ndig gekl\u00e4rt oder filtriert wurde. Auch Proteine und Tannine, die in einigen Weinen enthalten sind, k\u00f6nnen sich im Laufe der Zeit absetzen, besonders wenn keine Kl\u00e4rung oder vollst\u00e4ndige Filtration stattgefunden hat.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"450\" src=\"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image.png\" alt=\"\" class=\"wp-image-64782\" srcset=\"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image.png 338w, https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image-222x296.png 222w, https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image-75x100.png 75w\" sizes=\"auto, (max-width: 338px) 100vw, 338px\" \/><\/figure>\n\n<p>Die Bildung von Ablagerungen kann durch verschiedene Faktoren beeinflusst werden, darunter die Rebsorte, die Weinherstellungstechniken, der Kl\u00e4rungs- und Filtrationsprozess sowie die Lagerbedingungen des Weins.<\/p>\n\n<p>Wenn &#8222;Ablagerungen&#8220; vorhanden sind, sammeln sie sich am Boden der Flasche in Form von R\u00fcckst\u00e4nden an und zeigen sich als kleine Tr\u00fcmmer oder als Schleier, je nach Menge und Art der Substanzen, aus denen sie bestehen.<\/p>\n\n<p>Um die visuelle Auswirkung der Ablagerungen w\u00e4hrend der Verkostung zu minimieren, wird empfohlen, die Flasche vorsichtig zu handhaben, jegliches Sch\u00fctteln zu vermeiden und so die R\u00fcckst\u00e4nde m\u00f6glichst zusammengehalten und kompakt am Boden der Flasche zu halten.<\/p>\n\n<p>Bei reiferen Weinen oder solchen mit besonders auff\u00e4lligen R\u00fcckst\u00e4nden ist es \u00fcblich, den Wein zu dekantieren, d.h. ihn in einen Dekanter oder ein anderes Gef\u00e4\u00df zu gie\u00dfen, vorzugsweise nachdem er bel\u00fcftet wurde, um so die Sedimente vom Wein zu trennen und einen klareren Trinkgenuss zu erm\u00f6glichen.<\/p>\n\n<p>Es ist wichtig zu beachten, dass die R\u00fcckst\u00e4nde, \u00fcber die wir gesprochen haben, obwohl sie uns visuell st\u00f6ren k\u00f6nnen, nicht notwendigerweise auf einen fehlerhaften Wein hindeuten.<\/p>\n\n<p>Im Gegenteil, in einigen F\u00e4llen werden sie als Zeichen der Authentizit\u00e4t angesehen und k\u00f6nnen sogar die Komplexit\u00e4t des Weins erh\u00f6hen, insbesondere bei reiferen Weinen.<\/p>\n\n<p>Wir empfehlen daher, bei den Weinen, die Sie trinken, besondere Aufmerksamkeit auf die R\u00fcckst\u00e4nde zu legen, die sich in einer Flasche befinden k\u00f6nnen. Diese sollten nicht notwendigerweise als Probleme des Weins oder als eigentliche M\u00e4ngel betrachtet werden, sondern eher als ein charakteristisches Zeichen f\u00fcr die Qualit\u00e4t und die Herkunft des Weins selbst.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e4ufig k\u00f6nnen in Weinen, insbesondere bei Rotweinen und einige Jahre nach der Ernte, Unvollkommenheiten bei der visuellen Untersuchung aufgrund von R\u00fcckst\u00e4nden oder Sedimenten festgestellt werden, die gemeinhin als &#8222;Bodensatz&#8220; bezeichnet werden, weil sie sich am Boden der Flasche absetzen. Die Bildung dieser Ablagerungen wird durch einen nat\u00fcrlichen Prozess verursacht, der durch die Aggregation und nachfolgende [&#8230;]\n","protected":false},"author":216,"featured_media":64781,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[327,472],"tags":[],"class_list":["post-65076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anmerkungen-des-sommeliers","category-les-notes-du-sommelier-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Was sind Wein-&quot;Ablagerungen&quot;? | Torri Cantine Store<\/title>\n<meta name=\"description\" content=\"Sediments, die aufgrund ihrer Eigenschaft, sich am Boden der Flasche abzusetzen, \u00fcblicherweise &#039;posa&#039; genannt werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was sind Wein-&quot;Ablagerungen&quot;? | Torri Cantine Store\" \/>\n<meta property=\"og:description\" content=\"Sediments, die aufgrund ihrer Eigenschaft, sich am Boden der Flasche abzusetzen, \u00fcblicherweise &#039;posa&#039; genannt werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/\" \/>\n<meta property=\"og:site_name\" content=\"Torri Cantine Store COM\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-11T10:31:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-18T13:19:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image-1024x683-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Francesco Properzi Curti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Properzi Curti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/\"},\"author\":{\"name\":\"Francesco Properzi Curti\",\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/#\\\/schema\\\/person\\\/ccbed33468e1075084ce0e022224f77d\"},\"headline\":\"Was sind Wein-&#8222;Ablagerungen&#8220;?\",\"datePublished\":\"2024-01-11T10:31:35+00:00\",\"dateModified\":\"2024-06-18T13:19:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/\"},\"wordCount\":548,\"publisher\":{\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.torricantine.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/image-1024x683-1.png\",\"articleSection\":[\"Anmerkungen des Sommeliers\",\"Les notes du Sommelier\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/\",\"url\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/\",\"name\":\"Was sind Wein-\\\"Ablagerungen\\\"? | Torri Cantine Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/shop.torricantine.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/image-1024x683-1.png\",\"datePublished\":\"2024-01-11T10:31:35+00:00\",\"dateModified\":\"2024-06-18T13:19:26+00:00\",\"description\":\"Sediments, die aufgrund ihrer Eigenschaft, sich am Boden der Flasche abzusetzen, \u00fcblicherweise 'posa' genannt werden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/shop.torricantine.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/image-1024x683-1.png\",\"contentUrl\":\"https:\\\/\\\/shop.torricantine.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/image-1024x683-1.png\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/ablagerungen-im-wein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was sind Wein-&#8220;Ablagerungen&#8221;?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/\",\"name\":\"Torri Cantine Store COM\",\"description\":\"Online store of our winery in Italy\",\"publisher\":{\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/#organization\",\"name\":\"Torri Cantine\",\"url\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/shop.torricantine.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/torri-store-logo_text.png\",\"contentUrl\":\"https:\\\/\\\/shop.torricantine.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/torri-store-logo_text.png\",\"width\":289,\"height\":361,\"caption\":\"Torri Cantine\"},\"image\":{\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/#\\\/schema\\\/person\\\/ccbed33468e1075084ce0e022224f77d\",\"name\":\"Francesco Properzi Curti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/shop.torricantine.com\\\/wp-content\\\/litespeed\\\/avatar\\\/63125d59e78b6f8461b2600d03244fd5.jpg?ver=1778552069\",\"url\":\"https:\\\/\\\/shop.torricantine.com\\\/wp-content\\\/litespeed\\\/avatar\\\/63125d59e78b6f8461b2600d03244fd5.jpg?ver=1778552069\",\"contentUrl\":\"https:\\\/\\\/shop.torricantine.com\\\/wp-content\\\/litespeed\\\/avatar\\\/63125d59e78b6f8461b2600d03244fd5.jpg?ver=1778552069\",\"caption\":\"Francesco Properzi Curti\"},\"description\":\"Sommelier &amp; Wine Specialist\",\"url\":\"https:\\\/\\\/shop.torricantine.com\\\/de\\\/blog\\\/author\\\/francescoproperzicurti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was sind Wein-\"Ablagerungen\"? | Torri Cantine Store","description":"Sediments, die aufgrund ihrer Eigenschaft, sich am Boden der Flasche abzusetzen, \u00fcblicherweise 'posa' genannt werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/","og_locale":"de_DE","og_type":"article","og_title":"Was sind Wein-\"Ablagerungen\"? | Torri Cantine Store","og_description":"Sediments, die aufgrund ihrer Eigenschaft, sich am Boden der Flasche abzusetzen, \u00fcblicherweise 'posa' genannt werden.","og_url":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/","og_site_name":"Torri Cantine Store COM","article_published_time":"2024-01-11T10:31:35+00:00","article_modified_time":"2024-06-18T13:19:26+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image-1024x683-1.png","type":"image\/png"}],"author":"Francesco Properzi Curti","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Francesco Properzi Curti","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/#article","isPartOf":{"@id":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/"},"author":{"name":"Francesco Properzi Curti","@id":"https:\/\/shop.torricantine.com\/de\/#\/schema\/person\/ccbed33468e1075084ce0e022224f77d"},"headline":"Was sind Wein-&#8222;Ablagerungen&#8220;?","datePublished":"2024-01-11T10:31:35+00:00","dateModified":"2024-06-18T13:19:26+00:00","mainEntityOfPage":{"@id":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/"},"wordCount":548,"publisher":{"@id":"https:\/\/shop.torricantine.com\/de\/#organization"},"image":{"@id":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image-1024x683-1.png","articleSection":["Anmerkungen des Sommeliers","Les notes du Sommelier"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/","url":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/","name":"Was sind Wein-\"Ablagerungen\"? | Torri Cantine Store","isPartOf":{"@id":"https:\/\/shop.torricantine.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/#primaryimage"},"image":{"@id":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/#primaryimage"},"thumbnailUrl":"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image-1024x683-1.png","datePublished":"2024-01-11T10:31:35+00:00","dateModified":"2024-06-18T13:19:26+00:00","description":"Sediments, die aufgrund ihrer Eigenschaft, sich am Boden der Flasche abzusetzen, \u00fcblicherweise 'posa' genannt werden.","breadcrumb":{"@id":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/#primaryimage","url":"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image-1024x683-1.png","contentUrl":"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image-1024x683-1.png","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/shop.torricantine.com\/de\/blog\/ablagerungen-im-wein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/shop.torricantine.com\/de\/"},{"@type":"ListItem","position":2,"name":"Was sind Wein-&#8220;Ablagerungen&#8221;?"}]},{"@type":"WebSite","@id":"https:\/\/shop.torricantine.com\/de\/#website","url":"https:\/\/shop.torricantine.com\/de\/","name":"Torri Cantine Store COM","description":"Online store of our winery in Italy","publisher":{"@id":"https:\/\/shop.torricantine.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shop.torricantine.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/shop.torricantine.com\/de\/#organization","name":"Torri Cantine","url":"https:\/\/shop.torricantine.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/shop.torricantine.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2020\/04\/torri-store-logo_text.png","contentUrl":"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2020\/04\/torri-store-logo_text.png","width":289,"height":361,"caption":"Torri Cantine"},"image":{"@id":"https:\/\/shop.torricantine.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/shop.torricantine.com\/de\/#\/schema\/person\/ccbed33468e1075084ce0e022224f77d","name":"Francesco Properzi Curti","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/shop.torricantine.com\/wp-content\/litespeed\/avatar\/63125d59e78b6f8461b2600d03244fd5.jpg?ver=1778552069","url":"https:\/\/shop.torricantine.com\/wp-content\/litespeed\/avatar\/63125d59e78b6f8461b2600d03244fd5.jpg?ver=1778552069","contentUrl":"https:\/\/shop.torricantine.com\/wp-content\/litespeed\/avatar\/63125d59e78b6f8461b2600d03244fd5.jpg?ver=1778552069","caption":"Francesco Properzi Curti"},"description":"Sommelier &amp; Wine Specialist","url":"https:\/\/shop.torricantine.com\/de\/blog\/author\/francescoproperzicurti\/"}]}},"jetpack_featured_media_url":"https:\/\/shop.torricantine.com\/wp-content\/uploads\/2024\/01\/image-1024x683-1.png","_links":{"self":[{"href":"https:\/\/shop.torricantine.com\/de\/wp-json\/wp\/v2\/posts\/65076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.torricantine.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/shop.torricantine.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/shop.torricantine.com\/de\/wp-json\/wp\/v2\/users\/216"}],"replies":[{"embeddable":true,"href":"https:\/\/shop.torricantine.com\/de\/wp-json\/wp\/v2\/comments?post=65076"}],"version-history":[{"count":0,"href":"https:\/\/shop.torricantine.com\/de\/wp-json\/wp\/v2\/posts\/65076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.torricantine.com\/de\/wp-json\/wp\/v2\/media\/64781"}],"wp:attachment":[{"href":"https:\/\/shop.torricantine.com\/de\/wp-json\/wp\/v2\/media?parent=65076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/shop.torricantine.com\/de\/wp-json\/wp\/v2\/categories?post=65076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/shop.torricantine.com\/de\/wp-json\/wp\/v2\/tags?post=65076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}